{"id":14702,"date":"2025-10-07T07:25:00","date_gmt":"2025-10-07T12:25:00","guid":{"rendered":"https:\/\/www.abcsupply.com\/news-events\/lw-supply-anuncia-nuevo-presidente\/"},"modified":"2025-10-07T07:27:44","modified_gmt":"2025-10-07T12:27:44","slug":"lw-supply-anuncia-nuevo-presidente","status":"publish","type":"post","link":"https:\/\/www.abcsupply.com\/es\/news-events\/lw-supply-anuncia-nuevo-presidente\/","title":{"rendered":"L&amp;W Supply anuncia su nuevo presidente"},"content":{"rendered":"<p>ABC Supply anunci\u00f3 que Frank Marcoccio suceder\u00e1 a Dan Pich\u00e9 como presidente de L&amp;W Supply, un distribuidor mayorista nacional de materiales para la construcci\u00f3n y suministros para interiores. Esta transici\u00f3n tomar\u00e1 efecto a partir del 1 de enero de 2026 y dar\u00e1 continuidad al profundo impacto logrado durante la gesti\u00f3n de Pich\u00e9.<\/p>\n<p>\u00abDan ha dejado una huella duradera en L&amp;W Supply, pues impuls\u00f3 un crecimiento notable y construy\u00f3 una cultura anclada en nuestros Valores Centrales. Estamos agradecidos por su visi\u00f3n y compromiso a lo largo de los a\u00f1os,\u00bb coment\u00f3 Mike Jost, presidente y director de operaciones de ABC Supply. \u00abDe cara al futuro, pensamos que la genuina pasi\u00f3n que siente Frank por el negocio y su compromiso por fomentar una cultura de oportunidades y emprendedurismo lo convierten en el l\u00edder ideal para llevar adelante la pr\u00f3xima etapa de crecimiento de L&amp;W Supply.\u00bb<\/p>\n<p>Marcoccio aporta un amplio conocimiento de la industria de los materiales de la construcci\u00f3n, marcado por d\u00e9cadas de experiencia. Comenz\u00f3 su carrera apenas termin\u00f3 la universidad, y obtuvo as\u00ed experiencia pr\u00e1ctica empezando por roles iniciales, ocupando desde entonces puestos en ventas, gesti\u00f3n de sucursal y gesti\u00f3n de distritos. Luego de unirse a ABC Supply con la adquisici\u00f3n de L&amp;W Supply en 2010, progres\u00f3 en puestos clave, como el de gerente de negocios de techos de pendiente baja para la regi\u00f3n sureste, gerente de distrito de Georgia y vicepresidente de la regi\u00f3n sureste, donde supervis\u00f3 el desarrollo en 8 estados distintos. De forma m\u00e1s reciente, Marcoccio se desempe\u00f1\u00f3 como director administrativo de ABC Supply y director de operaciones de L&amp;W Supply.<\/p>\n<p>\u00abEs un honor asumir el cargo de presidente en un momento tan importante para nuestra empresa\u00bb, afirm\u00f3 Marcoccio. \u00abEl futuro es prometedor y est\u00e1 lleno de oportunidades, y me entusiasma la posibilidad de centrarme en liderar nuestros esfuerzos para aumentar nuestras ventas y expandir nuestra participaci\u00f3n en nuevos mercados. Nuestro compromiso con brindar un servicio de primer nivel, fomentar un esp\u00edritu emprendedor y ayudar a que nuestros empleados y clientes alcancen el \u00e9xito seguir\u00e1 siendo estando en el centro de todo lo que hacemos mientras procuramos tambi\u00e9n mantener la excelencia operativa en todo lo que hacemos. Gracias por la confianza y el apoyo que me brindan ahora que nos embarcamos en este emocionante viaje juntos.\u00bb<\/p>\n<p>Durante sus 18 a\u00f1os de trayectoria en ABC Supply, Pich\u00e9 ocup\u00f3 m\u00faltiples cargos de liderazgo, entre ellos el cargo de presidente de las filiales Mule-Hide Supply y L&amp;W Supply de ABC Supply. Bajo su liderazgo, L&amp;W Supply lleg\u00f3 a tener m\u00e1s del doble de sucursales que en el pasado, adquiri\u00f3 27 empresas y abri\u00f3 sucursales en 44 sucursales. La empresa tambi\u00e9n triplic\u00f3 su participaci\u00f3n de mercado y sus ventas, pasando a ocupar el tercer puesto en la industria y volvi\u00e9ndose as\u00ed en el mayor distribuidor mayorista de productos de yeso del pa\u00eds.<\/p>\n<p>\u00abEs hora de colgar los patines. Estoy ansioso por empezar mi vida en la granja\u00bb, coment\u00f3 Pich\u00e9. \u00abLuego de pasar 40 a\u00f1os en el sector de los materiales de construcci\u00f3n, voy a extra\u00f1ar las amistades, la industria y la competencia por ganar los corazones y las mentes de nuestros clientes. Quiero agradecer a todas las personas que confiaron en m\u00ed y me apoyaron en el proceso de convertir a L&amp;W en el principal distribuidor mayorista de productos de yeso de la industria. El futuro se ve muy prometedor con Frank al mando.\u00bb<\/p>\n<p>Mientras Marcoccio asume su rol, L&amp;W Supply se encuentra en una buena posici\u00f3n para seguir cosechando \u00e9xitos en los pr\u00f3ximos a\u00f1os. Dan seguir\u00e1 apoyando a Frank durante esta transici\u00f3n, orient\u00e1ndolo con seguridad y garantizando as\u00ed una transici\u00f3n sin contratiempos que prepare al equipo para seguir creciendo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Frank Marcoccio suceder\u00e1 a Dan Pich\u00e9 como presidente de L&amp;W Supply a partir del 1 de enero de 2026.<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[119],"tags":[],"class_list":["post-14702","post","type-post","status-publish","format-standard","hentry","category-noticias-de-la-empresa"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>L&amp;W Supply anuncia su nuevo presidente - ABC Supply<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.abcsupply.com\/es\/news-events\/lw-supply-anuncia-nuevo-presidente\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L&amp;W Supply anuncia su nuevo presidente - ABC Supply\" \/>\n<meta property=\"og:description\" content=\"Frank Marcoccio suceder\u00e1 a Dan Pich\u00e9 como presidente de L&amp;W Supply a partir del 1 de enero de 2026.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.abcsupply.com\/es\/news-events\/lw-supply-anuncia-nuevo-presidente\/\" \/>\n<meta property=\"og:site_name\" content=\"ABC Supply\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-07T12:25:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-07T12:27:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.abcsupply.com\/wp-content\/uploads\/2021\/09\/NSC-sharp.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1440\" \/>\n\t<meta property=\"og:image:height\" content=\"460\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jessica Kettle\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jessica Kettle\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.abcsupply.com\\\/es\\\/news-events\\\/lw-supply-anuncia-nuevo-presidente\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.abcsupply.com\\\/es\\\/news-events\\\/lw-supply-anuncia-nuevo-presidente\\\/\"},\"author\":{\"name\":\"Jessica Kettle\",\"@id\":\"https:\\\/\\\/www.abcsupply.com\\\/es\\\/#\\\/schema\\\/person\\\/c8acafe0f212b3af93fb46314a21c6f6\"},\"headline\":\"L&amp;W Supply anuncia su nuevo presidente\",\"datePublished\":\"2025-10-07T12:25:00+00:00\",\"dateModified\":\"2025-10-07T12:27:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.abcsupply.com\\\/es\\\/news-events\\\/lw-supply-anuncia-nuevo-presidente\\\/\"},\"wordCount\":661,\"articleSection\":[\"Noticias de la empresa\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.abcsupply.com\\\/es\\\/news-events\\\/lw-supply-anuncia-nuevo-presidente\\\/\",\"url\":\"https:\\\/\\\/www.abcsupply.com\\\/es\\\/news-events\\\/lw-supply-anuncia-nuevo-presidente\\\/\",\"name\":\"L&amp;W Supply anuncia su nuevo presidente - ABC Supply\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.abcsupply.com\\\/es\\\/#website\"},\"datePublished\":\"2025-10-07T12:25:00+00:00\",\"dateModified\":\"2025-10-07T12:27:44+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.abcsupply.com\\\/es\\\/#\\\/schema\\\/person\\\/c8acafe0f212b3af93fb46314a21c6f6\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.abcsupply.com\\\/es\\\/news-events\\\/lw-supply-anuncia-nuevo-presidente\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.abcsupply.com\\\/es\\\/news-events\\\/lw-supply-anuncia-nuevo-presidente\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.abcsupply.com\\\/es\\\/news-events\\\/lw-supply-anuncia-nuevo-presidente\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/www.abcsupply.com\\\/es\\\/casa\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"L&amp;W Supply anuncia su nuevo presidente\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.abcsupply.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.abcsupply.com\\\/es\\\/\",\"name\":\"ABC Supply\",\"description\":\"Built On A Foundation Of Respect\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.abcsupply.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.abcsupply.com\\\/es\\\/#\\\/schema\\\/person\\\/c8acafe0f212b3af93fb46314a21c6f6\",\"name\":\"Jessica Kettle\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/30c53ebd6c55d2c248a140f6f18ce7e7d5a7d699ba95102909beda85ac03656d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/30c53ebd6c55d2c248a140f6f18ce7e7d5a7d699ba95102909beda85ac03656d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/30c53ebd6c55d2c248a140f6f18ce7e7d5a7d699ba95102909beda85ac03656d?s=96&d=mm&r=g\",\"caption\":\"Jessica Kettle\"},\"url\":\"https:\\\/\\\/www.abcsupply.com\\\/es\\\/news-events\\\/author\\\/jessica-kettle-abc\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"L&amp;W Supply anuncia su nuevo presidente - ABC Supply","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.abcsupply.com\/es\/news-events\/lw-supply-anuncia-nuevo-presidente\/","og_locale":"es_ES","og_type":"article","og_title":"L&amp;W Supply anuncia su nuevo presidente - ABC Supply","og_description":"Frank Marcoccio suceder\u00e1 a Dan Pich\u00e9 como presidente de L&amp;W Supply a partir del 1 de enero de 2026.","og_url":"https:\/\/www.abcsupply.com\/es\/news-events\/lw-supply-anuncia-nuevo-presidente\/","og_site_name":"ABC Supply","article_published_time":"2025-10-07T12:25:00+00:00","article_modified_time":"2025-10-07T12:27:44+00:00","og_image":[{"width":1440,"height":460,"url":"https:\/\/www.abcsupply.com\/wp-content\/uploads\/2021\/09\/NSC-sharp.jpg","type":"image\/jpeg"}],"author":"Jessica Kettle","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Jessica Kettle","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.abcsupply.com\/es\/news-events\/lw-supply-anuncia-nuevo-presidente\/#article","isPartOf":{"@id":"https:\/\/www.abcsupply.com\/es\/news-events\/lw-supply-anuncia-nuevo-presidente\/"},"author":{"name":"Jessica Kettle","@id":"https:\/\/www.abcsupply.com\/es\/#\/schema\/person\/c8acafe0f212b3af93fb46314a21c6f6"},"headline":"L&amp;W Supply anuncia su nuevo presidente","datePublished":"2025-10-07T12:25:00+00:00","dateModified":"2025-10-07T12:27:44+00:00","mainEntityOfPage":{"@id":"https:\/\/www.abcsupply.com\/es\/news-events\/lw-supply-anuncia-nuevo-presidente\/"},"wordCount":661,"articleSection":["Noticias de la empresa"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.abcsupply.com\/es\/news-events\/lw-supply-anuncia-nuevo-presidente\/","url":"https:\/\/www.abcsupply.com\/es\/news-events\/lw-supply-anuncia-nuevo-presidente\/","name":"L&amp;W Supply anuncia su nuevo presidente - ABC Supply","isPartOf":{"@id":"https:\/\/www.abcsupply.com\/es\/#website"},"datePublished":"2025-10-07T12:25:00+00:00","dateModified":"2025-10-07T12:27:44+00:00","author":{"@id":"https:\/\/www.abcsupply.com\/es\/#\/schema\/person\/c8acafe0f212b3af93fb46314a21c6f6"},"breadcrumb":{"@id":"https:\/\/www.abcsupply.com\/es\/news-events\/lw-supply-anuncia-nuevo-presidente\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.abcsupply.com\/es\/news-events\/lw-supply-anuncia-nuevo-presidente\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.abcsupply.com\/es\/news-events\/lw-supply-anuncia-nuevo-presidente\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/www.abcsupply.com\/es\/casa\/"},{"@type":"ListItem","position":2,"name":"L&amp;W Supply anuncia su nuevo presidente"}]},{"@type":"WebSite","@id":"https:\/\/www.abcsupply.com\/es\/#website","url":"https:\/\/www.abcsupply.com\/es\/","name":"ABC Supply","description":"Built On A Foundation Of Respect","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.abcsupply.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.abcsupply.com\/es\/#\/schema\/person\/c8acafe0f212b3af93fb46314a21c6f6","name":"Jessica Kettle","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/30c53ebd6c55d2c248a140f6f18ce7e7d5a7d699ba95102909beda85ac03656d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/30c53ebd6c55d2c248a140f6f18ce7e7d5a7d699ba95102909beda85ac03656d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/30c53ebd6c55d2c248a140f6f18ce7e7d5a7d699ba95102909beda85ac03656d?s=96&d=mm&r=g","caption":"Jessica Kettle"},"url":"https:\/\/www.abcsupply.com\/es\/news-events\/author\/jessica-kettle-abc\/"}]}},"_links":{"self":[{"href":"https:\/\/www.abcsupply.com\/es\/wp-json\/wp\/v2\/posts\/14702","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.abcsupply.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.abcsupply.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.abcsupply.com\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.abcsupply.com\/es\/wp-json\/wp\/v2\/comments?post=14702"}],"version-history":[{"count":0,"href":"https:\/\/www.abcsupply.com\/es\/wp-json\/wp\/v2\/posts\/14702\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.abcsupply.com\/es\/wp-json\/wp\/v2\/media?parent=14702"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.abcsupply.com\/es\/wp-json\/wp\/v2\/categories?post=14702"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.abcsupply.com\/es\/wp-json\/wp\/v2\/tags?post=14702"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}